{"id":2411,"date":"2025-11-24T17:39:31","date_gmt":"2025-11-24T15:39:31","guid":{"rendered":"https:\/\/unionprofesionaldegalicia.org\/?p=2411"},"modified":"2025-11-24T17:40:53","modified_gmt":"2025-11-24T15:40:53","slug":"union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer","status":"publish","type":"post","link":"https:\/\/unionprofesionaldegalicia.org\/gl\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\/","title":{"rendered":"Uni\u00f3n Profesional de Galicia contra la violencia hacia la mujer"},"content":{"rendered":"\n[et_pb_section fb_built=\u00bb1&#8243; theme_builder_area=\u00bbpost_content\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||0px|||\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_image src=\u00bbhttps:\/\/unionprofesionaldegalicia.org\/wp-content\/uploads\/2025\/11\/Mujer-UPG.jpg\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb title_text=\u00bbMujer-UPG\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h1>Uni\u00f3n Profesional de Galicia contra la violencia hacia la mujer<\/h1>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Uni\u00f3n profesional de Galicia, desea expresar un a\u00f1o m\u00e1s su solidaridad con todas las mujeres que padecen alg\u00fan tipo de violencia, y expresa su convencimiento de que adem\u00e1s de las medidas necesarias, es preciso concienciar a la sociedad de que todos de alguna manera podemos contribuir de una manera efectiva para eliminar esta lacra de nuestra sociedad.<\/p>[\/et_pb_text][et_pb_divider _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb custom_padding=\u00bb0px|||||\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb2038e872-c347-4875-9be6-301ef144101e\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<h1>\u00daltimas noticias<\/h1>[\/et_pb_text][et_pb_blog fullwidth=\u00bboff\u00bb posts_number=\u00bb3&#8243; include_categories=\u00bball\u00bb show_author=\u00bboff\u00bb show_date=\u00bboff\u00bb show_categories=\u00bboff\u00bb show_excerpt=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_blog][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Uni\u00f3n Profesional de Galicia contra la violencia hacia la mujerUni\u00f3n profesional de Galicia, desea expresar un a\u00f1o m\u00e1s su solidaridad con todas las mujeres que padecen alg\u00fan tipo de violencia, y expresa su convencimiento de que adem\u00e1s de las medidas necesarias, es preciso concienciar a la sociedad de que todos de alguna manera podemos contribuir [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2413,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"1080","footnotes":""},"categories":[41],"tags":[],"class_list":["post-2411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-union-profesional-de-galicia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uni\u00f3n Profesional de Galicia contra la violencia hacia la mujer - Uni\u00f3n Profesional de Galicia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unionprofesionaldegalicia.org\/gl\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uni\u00f3n Profesional de Galicia contra la violencia hacia la mujer - Uni\u00f3n Profesional de Galicia\" \/>\n<meta property=\"og:description\" content=\"Uni\u00f3n Profesional de Galicia contra la violencia hacia la mujerUni\u00f3n profesional de Galicia, desea expresar un a\u00f1o m\u00e1s su solidaridad con todas las mujeres que padecen alg\u00fan tipo de violencia, y expresa su convencimiento de que adem\u00e1s de las medidas necesarias, es preciso concienciar a la sociedad de que todos de alguna manera podemos contribuir [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unionprofesionaldegalicia.org\/gl\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\/\" \/>\n<meta property=\"og:site_name\" content=\"Uni\u00f3n Profesional de Galicia\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-24T15:39:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-24T15:40:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unionprofesionaldegalicia.org\/wp-content\/uploads\/2025\/11\/Mujer-UPG.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Miguel Fern\u00e1ndez Castro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miguel Fern\u00e1ndez Castro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\\\/\"},\"author\":{\"name\":\"Miguel Fern\u00e1ndez Castro\",\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/#\\\/schema\\\/person\\\/1f5f151f1b6733621ffef1586f99d1e0\"},\"headline\":\"Uni\u00f3n Profesional de Galicia contra la violencia hacia la mujer\",\"datePublished\":\"2025-11-24T15:39:31+00:00\",\"dateModified\":\"2025-11-24T15:40:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\\\/\"},\"wordCount\":391,\"publisher\":{\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Mujer-UPG.jpg\",\"articleSection\":[\"Noticias Uni\u00f3n Profesional de Galicia\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\\\/\",\"url\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\\\/\",\"name\":\"Uni\u00f3n Profesional de Galicia contra la violencia hacia la mujer - Uni\u00f3n Profesional de Galicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Mujer-UPG.jpg\",\"datePublished\":\"2025-11-24T15:39:31+00:00\",\"dateModified\":\"2025-11-24T15:40:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Mujer-UPG.jpg\",\"contentUrl\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Mujer-UPG.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uni\u00f3n Profesional de Galicia contra la violencia hacia la mujer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/#website\",\"url\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/\",\"name\":\"Uni\u00f3n Profesional de Galicia\",\"description\":\"La Uni\u00f3n Profesional de Galicia es la entidad que agrupa a 44 colegios profesionales y act\u00faa como nexo entre ellos y la Administraci\u00f3n para impulsar iniciativas que fortalecen el ejercicio profesional y mejoran la actividad judicial.\",\"publisher\":{\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/#organization\",\"name\":\"Uni\u00f3n Profesional de Galicia\",\"url\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Logo-Union-Profesional.jpg\",\"contentUrl\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Logo-Union-Profesional.jpg\",\"width\":200,\"height\":71,\"caption\":\"Uni\u00f3n Profesional de Galicia\"},\"image\":{\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/#\\\/schema\\\/person\\\/1f5f151f1b6733621ffef1586f99d1e0\",\"name\":\"Miguel Fern\u00e1ndez Castro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56b998da338d19949582cc65096ee27ca386ba244f98bd3a6912608ca1f77a9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56b998da338d19949582cc65096ee27ca386ba244f98bd3a6912608ca1f77a9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56b998da338d19949582cc65096ee27ca386ba244f98bd3a6912608ca1f77a9a?s=96&d=mm&r=g\",\"caption\":\"Miguel Fern\u00e1ndez Castro\"},\"sameAs\":[\"https:\\\/\\\/gestudiosmultimedia.com\"],\"url\":\"https:\\\/\\\/unionprofesionaldegalicia.org\\\/gl\\\/author\\\/miguelgestudiosmultimedia-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uni\u00f3n Profesional de Galicia contra la violencia hacia la mujer - Uni\u00f3n Profesional de Galicia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unionprofesionaldegalicia.org\/gl\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\/","og_locale":"gl_ES","og_type":"article","og_title":"Uni\u00f3n Profesional de Galicia contra la violencia hacia la mujer - Uni\u00f3n Profesional de Galicia","og_description":"Uni\u00f3n Profesional de Galicia contra la violencia hacia la mujerUni\u00f3n profesional de Galicia, desea expresar un a\u00f1o m\u00e1s su solidaridad con todas las mujeres que padecen alg\u00fan tipo de violencia, y expresa su convencimiento de que adem\u00e1s de las medidas necesarias, es preciso concienciar a la sociedad de que todos de alguna manera podemos contribuir [&hellip;]","og_url":"https:\/\/unionprofesionaldegalicia.org\/gl\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\/","og_site_name":"Uni\u00f3n Profesional de Galicia","article_published_time":"2025-11-24T15:39:31+00:00","article_modified_time":"2025-11-24T15:40:53+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/unionprofesionaldegalicia.org\/wp-content\/uploads\/2025\/11\/Mujer-UPG.jpg","type":"image\/jpeg"}],"author":"Miguel Fern\u00e1ndez Castro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Miguel Fern\u00e1ndez Castro","Tempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/unionprofesionaldegalicia.org\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\/#article","isPartOf":{"@id":"https:\/\/unionprofesionaldegalicia.org\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\/"},"author":{"name":"Miguel Fern\u00e1ndez Castro","@id":"https:\/\/unionprofesionaldegalicia.org\/#\/schema\/person\/1f5f151f1b6733621ffef1586f99d1e0"},"headline":"Uni\u00f3n Profesional de Galicia contra la violencia hacia la mujer","datePublished":"2025-11-24T15:39:31+00:00","dateModified":"2025-11-24T15:40:53+00:00","mainEntityOfPage":{"@id":"https:\/\/unionprofesionaldegalicia.org\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\/"},"wordCount":391,"publisher":{"@id":"https:\/\/unionprofesionaldegalicia.org\/#organization"},"image":{"@id":"https:\/\/unionprofesionaldegalicia.org\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\/#primaryimage"},"thumbnailUrl":"https:\/\/unionprofesionaldegalicia.org\/wp-content\/uploads\/2025\/11\/Mujer-UPG.jpg","articleSection":["Noticias Uni\u00f3n Profesional de Galicia"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/unionprofesionaldegalicia.org\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\/","url":"https:\/\/unionprofesionaldegalicia.org\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\/","name":"Uni\u00f3n Profesional de Galicia contra la violencia hacia la mujer - Uni\u00f3n Profesional de Galicia","isPartOf":{"@id":"https:\/\/unionprofesionaldegalicia.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unionprofesionaldegalicia.org\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\/#primaryimage"},"image":{"@id":"https:\/\/unionprofesionaldegalicia.org\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\/#primaryimage"},"thumbnailUrl":"https:\/\/unionprofesionaldegalicia.org\/wp-content\/uploads\/2025\/11\/Mujer-UPG.jpg","datePublished":"2025-11-24T15:39:31+00:00","dateModified":"2025-11-24T15:40:53+00:00","breadcrumb":{"@id":"https:\/\/unionprofesionaldegalicia.org\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unionprofesionaldegalicia.org\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/unionprofesionaldegalicia.org\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\/#primaryimage","url":"https:\/\/unionprofesionaldegalicia.org\/wp-content\/uploads\/2025\/11\/Mujer-UPG.jpg","contentUrl":"https:\/\/unionprofesionaldegalicia.org\/wp-content\/uploads\/2025\/11\/Mujer-UPG.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/unionprofesionaldegalicia.org\/union-profesional-de-galicia-contra-la-violencia-hacia-la-mujer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/unionprofesionaldegalicia.org\/"},{"@type":"ListItem","position":2,"name":"Uni\u00f3n Profesional de Galicia contra la violencia hacia la mujer"}]},{"@type":"WebSite","@id":"https:\/\/unionprofesionaldegalicia.org\/#website","url":"https:\/\/unionprofesionaldegalicia.org\/","name":"Uni\u00f3n Profesional de Galicia","description":"La Uni\u00f3n Profesional de Galicia es la entidad que agrupa a 44 colegios profesionales y act\u00faa como nexo entre ellos y la Administraci\u00f3n para impulsar iniciativas que fortalecen el ejercicio profesional y mejoran la actividad judicial.","publisher":{"@id":"https:\/\/unionprofesionaldegalicia.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unionprofesionaldegalicia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/unionprofesionaldegalicia.org\/#organization","name":"Uni\u00f3n Profesional de Galicia","url":"https:\/\/unionprofesionaldegalicia.org\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/unionprofesionaldegalicia.org\/#\/schema\/logo\/image\/","url":"https:\/\/unionprofesionaldegalicia.org\/wp-content\/uploads\/2024\/12\/Logo-Union-Profesional.jpg","contentUrl":"https:\/\/unionprofesionaldegalicia.org\/wp-content\/uploads\/2024\/12\/Logo-Union-Profesional.jpg","width":200,"height":71,"caption":"Uni\u00f3n Profesional de Galicia"},"image":{"@id":"https:\/\/unionprofesionaldegalicia.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/unionprofesionaldegalicia.org\/#\/schema\/person\/1f5f151f1b6733621ffef1586f99d1e0","name":"Miguel Fern\u00e1ndez Castro","image":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/56b998da338d19949582cc65096ee27ca386ba244f98bd3a6912608ca1f77a9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/56b998da338d19949582cc65096ee27ca386ba244f98bd3a6912608ca1f77a9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56b998da338d19949582cc65096ee27ca386ba244f98bd3a6912608ca1f77a9a?s=96&d=mm&r=g","caption":"Miguel Fern\u00e1ndez Castro"},"sameAs":["https:\/\/gestudiosmultimedia.com"],"url":"https:\/\/unionprofesionaldegalicia.org\/gl\/author\/miguelgestudiosmultimedia-com\/"}]}},"_links":{"self":[{"href":"https:\/\/unionprofesionaldegalicia.org\/gl\/wp-json\/wp\/v2\/posts\/2411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unionprofesionaldegalicia.org\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unionprofesionaldegalicia.org\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unionprofesionaldegalicia.org\/gl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/unionprofesionaldegalicia.org\/gl\/wp-json\/wp\/v2\/comments?post=2411"}],"version-history":[{"count":4,"href":"https:\/\/unionprofesionaldegalicia.org\/gl\/wp-json\/wp\/v2\/posts\/2411\/revisions"}],"predecessor-version":[{"id":2416,"href":"https:\/\/unionprofesionaldegalicia.org\/gl\/wp-json\/wp\/v2\/posts\/2411\/revisions\/2416"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unionprofesionaldegalicia.org\/gl\/wp-json\/wp\/v2\/media\/2413"}],"wp:attachment":[{"href":"https:\/\/unionprofesionaldegalicia.org\/gl\/wp-json\/wp\/v2\/media?parent=2411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unionprofesionaldegalicia.org\/gl\/wp-json\/wp\/v2\/categories?post=2411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unionprofesionaldegalicia.org\/gl\/wp-json\/wp\/v2\/tags?post=2411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}